{"id":41,"date":"2020-01-14T15:32:55","date_gmt":"2020-01-14T14:32:55","guid":{"rendered":"https:\/\/www.tv-termine.de\/blog\/?p=41"},"modified":"2020-01-14T17:10:07","modified_gmt":"2020-01-14T16:10:07","slug":"neue-serie-timeless-startet","status":"publish","type":"post","link":"https:\/\/www.tv-termine.de\/blog\/neue-serie-timeless-startet\/","title":{"rendered":"Neue Serie Timeless startet auf Tele 5"},"content":{"rendered":"\n<h2>Zeitreise Serie &#8222;Timeless&#8220; startet auf Tele 5<\/h2>\n\n\n\n<p>Am Samstag starte auf Tele 5 eine neue Zeitreise Serie. Es geht um einen ex NSA Agenten, der eine Zeitmaschine gestohlen hat. Mit hilfe dieser versucht er die Geschichte zu ver\u00e4ndern. Gleich in der 1. Folge geht es um das Luftschiff &#8222;Hindenburg&#8220;. In der 2. Folge geht es um das Attentat auf Abraham Lincoln. Damit die Zeitlinie nicht kollabiert und die Gegenwart sich ver\u00e4ndert, wird eine Geschichts Professorin mit einer 2. Maschine hinterher geschickt. Sie soll Manipulationen der Vergangenheit verhindern.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"fitvids-video\"><iframe title=\"Timeless (NBC) Trailer HD\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/zSYZJGAGvww?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h2>Wie viele Folgen hat Staffel 1 ?<\/h2>\n\n\n\n<p>Staffel 1 beinhaltet insgesamt 16 Folgen. Staffel 2 hingegen kommt nur auf 10 Folgen<\/p>\n\n\n\n<h2>Wurde die Serie schon eingestellt ?<\/h2>\n\n\n\n<p>Nein bisher nicht, eine 2. Staffel wurde auch schon produziert. Es gibt also weitere Zeitreise Episoden. Staffel 3 soll auch noch folgen.<\/p>\n\n\n\n<h2>Wann genau l\u00e4uft die Serie ?<\/h2>\n\n\n\n<p>Jeden Samstag um 16:25 l\u00e4uft eine neue Folge der Serie auf Tele 5. Mehr Infos zu Ausstrahlungsterminen finden sie nat\u00fcrlich auf unserer Seite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zeitreise Serie &#8222;Timeless&#8220; startet auf Tele 5 Am Samstag starte auf Tele 5 eine neue Zeitreise Serie. Es geht um<\/p>\n","protected":false},"author":1,"featured_media":52,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Neue Serie Timeless startet auf Tele 5 - TV-Termine.de<\/title>\n<meta name=\"description\" content=\"Eine Scifi Zeitreise Serie startet am Samstag auf Tele 5\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tv-termine.de\/blog\/neue-serie-timeless-startet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neue Serie Timeless startet auf Tele 5 - TV-Termine.de\" \/>\n<meta property=\"og:description\" content=\"Eine Scifi Zeitreise Serie startet am Samstag auf Tele 5\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tv-termine.de\/blog\/neue-serie-timeless-startet\/\" \/>\n<meta property=\"og:site_name\" content=\"TV-Termine.de\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-14T14:32:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-14T16:10:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tv-termine.de\/blog\/wp-content\/uploads\/2020\/01\/timeless3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#website\",\"url\":\"https:\/\/www.tv-termine.de\/blog\/\",\"name\":\"TV-Termine.de\",\"description\":\"Infos zu Dokus + Serien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.tv-termine.de\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.tv-termine.de\/blog\/neue-serie-timeless-startet\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/www.tv-termine.de\/blog\/wp-content\/uploads\/2020\/01\/timeless3.jpg\",\"width\":630,\"height\":300},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tv-termine.de\/blog\/neue-serie-timeless-startet\/#webpage\",\"url\":\"https:\/\/www.tv-termine.de\/blog\/neue-serie-timeless-startet\/\",\"name\":\"Neue Serie Timeless startet auf Tele 5 - TV-Termine.de\",\"isPartOf\":{\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tv-termine.de\/blog\/neue-serie-timeless-startet\/#primaryimage\"},\"datePublished\":\"2020-01-14T14:32:55+00:00\",\"dateModified\":\"2020-01-14T16:10:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#\/schema\/person\/f042e60ba739188eadde602cfcae5070\"},\"description\":\"Eine Scifi Zeitreise Serie startet am Samstag auf Tele 5\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tv-termine.de\/blog\/neue-serie-timeless-startet\/\"]}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#\/schema\/person\/f042e60ba739188eadde602cfcae5070\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c301b50894665d962e40077af2ca00d8?s=96&d=mm&r=g\",\"caption\":\"Admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/posts\/41"}],"collection":[{"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":4,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/posts\/41\/revisions"}],"predecessor-version":[{"id":55,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/posts\/41\/revisions\/55"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/media\/52"}],"wp:attachment":[{"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/media?parent=41"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/categories?post=41"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/tags?post=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}