{"id":207,"date":"2020-09-03T00:48:39","date_gmt":"2020-09-02T22:48:39","guid":{"rendered":"https:\/\/www.tv-termine.de\/blog\/?p=207"},"modified":"2020-09-03T00:54:23","modified_gmt":"2020-09-02T22:54:23","slug":"2-neue-dokus-parker-in-australien-san-diego-zoo","status":"publish","type":"post","link":"https:\/\/www.tv-termine.de\/blog\/2-neue-dokus-parker-in-australien-san-diego-zoo\/","title":{"rendered":"2 neue Dokus &#8211; Parker in Australien &#038; San Diego Zoo"},"content":{"rendered":"\n<p>In den n\u00e4chsten Tagen starten 2 neue Dokus. Es geht um den Zoo von San Diegeo und Parker besucht Australien. Das ist seine 4. Reise wo ihm das Kamera Team begleitet.<\/p>\n\n\n\n<h3>San Diego Zoo auf TLC<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"960\" height=\"540\" src=\"https:\/\/www.tv-termine.de\/blog\/wp-content\/uploads\/2020\/09\/sandiego-zoo.jpg\" alt=\"\" class=\"wp-image-211\" srcset=\"https:\/\/www.tv-termine.de\/blog\/wp-content\/uploads\/2020\/09\/sandiego-zoo.jpg 960w, https:\/\/www.tv-termine.de\/blog\/wp-content\/uploads\/2020\/09\/sandiego-zoo-300x169.jpg 300w, https:\/\/www.tv-termine.de\/blog\/wp-content\/uploads\/2020\/09\/sandiego-zoo-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p>Auf TLC startet eine neue Zoo Doku mit dem Namen <strong>San Diego Zoo<\/strong>. Der Zoo befindet sich wie man am Namen erkennen kann in San Diego, Kalifornien, USA. Mit \u00fcber 3 Millionen Besucher ist er der meist besuchte Zoo der USA. \u00dcber 3.000 Tiere sind auf einer Fl\u00e4che von 40 Hektar zu sehen.<\/p>\n\n\n\n<p>Die 1. Staffel startet am Samstag den 05.09 um 13:20 auf TLC, mit der Folge <strong>Aus dem Ei geschl\u00fcpft<\/strong>. In der Folge warten die Tierpfleger gespannt, ob aus den Eiern Kalifornische Kondore schl\u00fcpfen.<\/p>\n\n\n\n<h3>Goldrausch: Parkers Australien-Abenteuer<\/h3>\n\n\n\n<p>Auf DMax startet Parker Schnabel mit einer neuen Ausgabe seiner Goldrausch Reihe. Diesmal schaut er sich an, wie in Australien nach Gold gesucht wird. Immer wenn in Alaska der Winter das Gold suchen verhindert, begibt sich Parker mit seinem Team auf Weltreise.<\/p>\n\n\n\n<p>Es ist die 4. Spezial Ausgabe, bisher hat er folgende Regionen besucht.<\/p>\n\n\n\n<ul><li>Klondike (Alaska)<\/li><li>Dschungel (Guyana)<\/li><li>Neuguinea<\/li><\/ul>\n\n\n\n<p>Im Klondike fing alles an, er besuchte die Orte, als der Goldrausch damals in Alaska begann. Dann reiste er in den Dschungel, und besuchte unter anderen die Stelle, wo die Hoffmans nach Gold suchten, und scheiterten. In der 3. Ausgabe reiste er nach Neuguinea und besuchte den Edie Creek, dort brach 1920 der gro\u00dfe Goldrausch in dem Land aus.<\/p>\n\n\n\n<p>Diesmal geht es also nach Australien, mit dem Detektor sucht er direkt an der Oberfl\u00e4che nach Nuggets. Dabei trifft er nat\u00fcrlich auch die Goldsucher aus der Doku <strong>Goldrausch in Australien<\/strong>. Zu sehen gibt es sein Abenteuer jeden Mittwoch um 21:15 auf Dmax. Er \u00fcbernimmt den Sendeplatz von <strong>Goldtaucher der Beringsee<\/strong>. Deren Staffel endete ja gestern.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den n\u00e4chsten Tagen starten 2 neue Dokus. Es geht um den Zoo von San Diegeo und Parker besucht Australien.<\/p>\n","protected":false},"author":1,"featured_media":212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>2 neue Dokus - Parker in Australien &amp; San Diego Zoo - TV-Termine.de<\/title>\n<meta name=\"description\" content=\"Zoogeschichten aus San Diego und Parker Schnabel ist zu Besuch in Australien, und schaut sich an, wie man in Australien nach Gold sucht.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tv-termine.de\/blog\/2-neue-dokus-parker-in-australien-san-diego-zoo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2 neue Dokus - Parker in Australien &amp; San Diego Zoo - TV-Termine.de\" \/>\n<meta property=\"og:description\" content=\"Zoogeschichten aus San Diego und Parker Schnabel ist zu Besuch in Australien, und schaut sich an, wie man in Australien nach Gold sucht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tv-termine.de\/blog\/2-neue-dokus-parker-in-australien-san-diego-zoo\/\" \/>\n<meta property=\"og:site_name\" content=\"TV-Termine.de\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-02T22:48:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-02T22:54:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tv-termine.de\/blog\/wp-content\/uploads\/2020\/09\/szoo2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#website\",\"url\":\"https:\/\/www.tv-termine.de\/blog\/\",\"name\":\"TV-Termine.de\",\"description\":\"Infos zu Dokus + Serien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.tv-termine.de\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.tv-termine.de\/blog\/2-neue-dokus-parker-in-australien-san-diego-zoo\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/www.tv-termine.de\/blog\/wp-content\/uploads\/2020\/09\/szoo2.jpg\",\"width\":630,\"height\":300},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tv-termine.de\/blog\/2-neue-dokus-parker-in-australien-san-diego-zoo\/#webpage\",\"url\":\"https:\/\/www.tv-termine.de\/blog\/2-neue-dokus-parker-in-australien-san-diego-zoo\/\",\"name\":\"2 neue Dokus - Parker in Australien & San Diego Zoo - TV-Termine.de\",\"isPartOf\":{\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tv-termine.de\/blog\/2-neue-dokus-parker-in-australien-san-diego-zoo\/#primaryimage\"},\"datePublished\":\"2020-09-02T22:48:39+00:00\",\"dateModified\":\"2020-09-02T22:54:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#\/schema\/person\/f042e60ba739188eadde602cfcae5070\"},\"description\":\"Zoogeschichten aus San Diego und Parker Schnabel ist zu Besuch in Australien, und schaut sich an, wie man in Australien nach Gold sucht.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tv-termine.de\/blog\/2-neue-dokus-parker-in-australien-san-diego-zoo\/\"]}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#\/schema\/person\/f042e60ba739188eadde602cfcae5070\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.tv-termine.de\/blog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c301b50894665d962e40077af2ca00d8?s=96&d=mm&r=g\",\"caption\":\"Admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/posts\/207"}],"collection":[{"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":4,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"predecessor-version":[{"id":215,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/posts\/207\/revisions\/215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/media\/212"}],"wp:attachment":[{"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv-termine.de\/blog\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}